{"id":508,"date":"2019-02-18T09:41:28","date_gmt":"2019-02-18T08:41:28","guid":{"rendered":"http:\/\/dev.meyco.eu\/meyco\/?page_id=508"},"modified":"2026-02-27T10:25:27","modified_gmt":"2026-02-27T09:25:27","slug":"neuheiten","status":"publish","type":"page","link":"https:\/\/www.meyco.eu\/home\/neuheiten\/","title":{"rendered":"Neuheiten"},"content":{"rendered":"<div  data-label=\"Portfolio\" data-id=\"portfolio--1\" data-export-id=\"portfolio-6\" data-category=\"portfolio\" class=\"portfolio-6 content-section content-section-spacing\" id=\"portfolio-1\" style=\"background-color: rgb(255, 255, 255); background-image: none;\"><div  class=\"gridContainer\"> <div  class=\"row text-center\"><div  class=\"section-title-col\" data-type=\"column\"> <h2  class=\"\">Neuheiten &amp; Aktionen<\/h2> <p  class=\"lead\">Neuheiten &amp; Aktionen ab Hauptkatalog HK-D14<br ><br >Hier finden Sie Aktionswaren und alle Neuheiten, die wir nach Erscheinen des aktuellen Kataloges in unserem Sortiment aufgenommen haben ohne Preise. Die Preise erfragen Sie bitte bei Ihrem zust\u00e4ndigen Au\u00dfendienstmitarbeiter oder kontaktieren Sie uns. Wir weisen an dieser Stelle nochmals darauf hin, dass wir nur den Facheinzelhandel beliefern.<\/p><\/div> <\/div> <div  class=\"row space-bottom spaced-cols center-sm\" data-type=\"row\">    <div  class=\"col-xs-12 col-sm-4 text-center col-md-3\"><div  class=\"card no-padding \"> <div  data-hover-fx=\"portfolio-5\" class=\"contentswap-effect\"><div  class=\"initial-image\"> <img  decoding=\"async\" data-size=\"500x333\" src=\"https:\/\/www.meyco.eu\/home\/wp-content\/uploads\/2026\/02\/cropped-cropped-Cover_Ostern_2026.jpg\"><\/div> <div  class=\"overlay bg-color6\"><\/div> <div  class=\"swap-inner col-xs-12\"> <div  class=\"row full-height-row middle-xs middle-sm\"> <div  class=\"col-xs-12 text-center content-holder\"> <a  href=\"https:\/\/www.meyco.eu\/home\/wp-content\/uploads\/meyco-upload\/Ostern 2026_ohne_small.pdf\" target=\"_blank\" class=\"\" rel=\"noopener noreferrer\"><i  class=\"fa icon portfolio-icon fa-search reverse round big color-white\" aria-hidden=\"true\"><\/i><\/a><\/div> <\/div><\/div> <\/div> <div  class=\"space-bottom space-top col-xs-12\" data-type=\"column\"> <h4  class=\"\">Ostern 2026<\/h4> <p  class=\"small italic\">Zusammenstellung unserer&nbsp;<br >Saison Artikel<\/p><\/div> <\/div><\/div><\/div> <div  class=\"row\"> <div  data-type=\"column\" class=\"col-xs-12 text-center\"> <a  class=\"button y-move color2\" href=\"#\" target=\"_self\" data-cp-link=\"1\" data-icon=\"\" rel=\"noopener noreferrer\">nach oben<\/a><\/div> <\/div><\/div> <\/div>","protected":false},"excerpt":{"rendered":"<p>Neuheiten &amp; Aktionen Neuheiten &amp; Aktionen ab Hauptkatalog HK-D14Hier finden Sie Aktionswaren und alle Neuheiten, die wir nach Erscheinen des aktuellen Kataloges in unserem Sortiment aufgenommen haben ohne Preise. Die Preise erfragen Sie bitte bei Ihrem zust\u00e4ndigen Au\u00dfendienstmitarbeiter oder kontaktieren Sie uns. Wir weisen an dieser Stelle nochmals darauf hin, dass wir nur den Facheinzelhandel&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/www.meyco.eu\/home\/neuheiten\/\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":2657,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"pro\/page-templates\/full-width-page.php","meta":{"footnotes":""},"class_list":["post-508","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.meyco.eu\/home\/wp-json\/wp\/v2\/pages\/508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meyco.eu\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.meyco.eu\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.meyco.eu\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.meyco.eu\/home\/wp-json\/wp\/v2\/comments?post=508"}],"version-history":[{"count":90,"href":"https:\/\/www.meyco.eu\/home\/wp-json\/wp\/v2\/pages\/508\/revisions"}],"predecessor-version":[{"id":4653,"href":"https:\/\/www.meyco.eu\/home\/wp-json\/wp\/v2\/pages\/508\/revisions\/4653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.meyco.eu\/home\/wp-json\/wp\/v2\/media\/2657"}],"wp:attachment":[{"href":"https:\/\/www.meyco.eu\/home\/wp-json\/wp\/v2\/media?parent=508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}